                                                                                                                                                                                                                                                                                                                                                                                                                                         {"id":8584,"date":"2022-05-17T14:42:15","date_gmt":"2022-05-17T14:42:15","guid":{"rendered":"https:\/\/beongarden.com\/lojanova\/?post_type=product&#038;p=8584"},"modified":"2024-01-10T16:21:41","modified_gmt":"2024-01-10T16:21:41","slug":"guarda-sol-rio-4x4","status":"publish","type":"product","link":"https:\/\/loja.beongarden.com\/en\/produto\/guarda-sol-rio-4x4\/","title":{"rendered":"Guarda Sol &#8211; Rio 4&#215;4"},"content":{"rendered":"<p>Confecionado com tecido OLEFIN fabricado com fio em polipropileno tingido em massa no seu processo inicial, esta caracter\u00edstica confere-lhe uma maior resist\u00eancia \u00e0 luz solar o que se deve essencialmente ao facto de a cor permanecer fixada ao fio com maior intensidade do que em outros processos de pigmenta\u00e7\u00e3o. Certifica\u00e7\u00e3o UV standard 801 com fator de prote\u00e7\u00e3o UPF 80, que garante a prote\u00e7\u00e3o da pele dos efeitos nocivos dos raios UV.<\/p>\n<p>Caracter\u00edsticas:<br \/>\n-Material: Alum\u00ednio lacado<br \/>\n-8 varetas intercambi\u00e1veis (20x35x1,5 mm)<br \/>\n-Abertura assistida manivela<br \/>\n-Telesc\u00f3pico<br \/>\n-Com fuga ventos<br \/>\n-Repelente \u00e0 \u00e1gua<br \/>\n-Anti manchas<br \/>\n-100% recicl\u00e1vel<br \/>\n-Base n\u00e3o inclu\u00edda<br \/>\n-Muito f\u00e1cil de lavar e desinfetar<br \/>\n-Use em superf\u00edcies est\u00e1veis e planas<br \/>\n-Produto de uso p\u00fablico e dom\u00e9stico<\/p>\n<p><strong>Valor do transporte sob consulta.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Forte, resistente e de grandes dimens\u00f5es : este \u00e9 o guarda-sol RIO. A sua manivela permite-nos abri-lo e fech\u00e1-lo com facilidade.<\/p>\n","protected":false},"featured_media":11750,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[78,73],"product_tag":[],"_links":{"self":[{"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/product\/8584"}],"collection":[{"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/comments?post=8584"}],"version-history":[{"count":5,"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/product\/8584\/revisions"}],"predecessor-version":[{"id":13182,"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/product\/8584\/revisions\/13182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/media\/11750"}],"wp:attachment":[{"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/media?parent=8584"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/product_cat?post=8584"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/loja.beongarden.com\/en\/wp-json\/wp\/v2\/product_tag?post=8584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}